{"id":4423,"date":"2024-09-04T09:46:07","date_gmt":"2024-09-04T07:46:07","guid":{"rendered":"https:\/\/www.beco-bermueller.de\/?p=4423"},"modified":"2024-10-08T13:57:23","modified_gmt":"2024-10-08T11:57:23","slug":"wir-sind-auf-der-baugrundtagung-2024","status":"publish","type":"post","link":"https:\/\/n4zkkxq1zk.apb.spinupwp.site\/en\/wir-sind-auf-der-baugrundtagung-2024\/","title":{"rendered":"We are at the Baugrundtagung 2024!"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.24.3&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.24.3&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; custom_padding=&#8221;0px||||false|false&#8221; sticky_enabled=&#8221;0&#8243;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.24.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.24.3&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#00A286&#8243; text_font_size=&#8221;15px&#8221; text_letter_spacing=&#8221;0.3px&#8221; custom_margin=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p class=\"h4\">26.09.2024<\/p>\n<ol><\/ol>\n<p>[\/et_pb_text][et_pb_heading title=&#8221;Wir sind auf der Baugrundtagung 2024!&#8221; _builder_version=&#8221;4.24.3&#8243; _module_preset=&#8221;default&#8221; title_font=&#8221;Simplon Light||||||||&#8221; title_text_color=&#8221;#2B2B2A&#8221; title_font_size=&#8221;50px&#8221; title_letter_spacing=&#8221;0.3px&#8221; title_font_size_tablet=&#8221;60px&#8221; title_font_size_phone=&#8221;40px&#8221; title_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_text _builder_version=&#8221;4.24.3&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#2B2B2A&#8221; text_font_size=&#8221;17px&#8221; text_letter_spacing=&#8221;0.3px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p class=\"h4\"><span>Besuchen Sie uns auf der Fachausstellung Geotechnik der 38. Baugrundtagung des DGGT vom\u00a0<\/span><strong>26. &#8211; 27. September 2024<\/strong><span>\u00a0in Bremen<\/span><\/p>\n<ol><\/ol>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.24.3&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/n4zkkxq1zk.apb.spinupwp.site\/wp-content\/uploads\/2024\/09\/beco_baugrundtagug_2024.991&#215;0-generated_80-jpg.webp&#8221; alt=&#8221;beco_baugrundtagug&#8221; title_text=&#8221;beco_baugrundtagug&#8221; _builder_version=&#8221;4.24.3&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;||||false|false&#8221; custom_css_free_form=&#8221;.custom-image-overlay:after {||    content: %22%22;||    display: block;||    position: absolute;||    top: 0; \/* Oben am Bild ausgerichtet *\/||    right: 0; \/* Am rechten Rand des Bildes *\/||    bottom: 0; \/* Unten am Bild ausgerichtet *\/||    width: 23%; \/* Breite des Overlays *\/||  mix-blend-mode: multiply;||    background: rgba(0, 162, 134, 1);||    z-index: 1;||}||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;off|tablet&#8221; admin_label=&#8221;section&#8221; _builder_version=&#8221;4.24.3&#8243; background_enable_color=&#8221;off&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;10px||10px||false|false&#8221; custom_padding_tablet=&#8221;20px||0px||false|false&#8221; custom_padding_phone=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row custom_padding_last_edited=&#8221;off|desktop&#8221; _builder_version=&#8221;4.24.3&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;1440px&#8221; custom_padding=&#8221;0px|0px|0px|0px|false|true&#8221; custom_padding_tablet=&#8221;0px|60px||60px|false|true&#8221; custom_padding_phone=&#8221;|30px||30px|false|true&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.24.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][lwp_divi_breadcrumbs home_text=&#8221;Startseite&#8221; font_icon=&#8221;&#x35;||divi||400&#8243; use_before_icon=&#8221;off&#8221; use_custom_home_link=&#8221;off&#8221; link_color=&#8221;#2B2B2A&#8221; separator_color=&#8221;#2B2B2A&#8221; current_text_color=&#8221;#00A286&#8243; _builder_version=&#8221;4.24.3&#8243; _module_preset=&#8221;default&#8221; module_font=&#8221;Simplon Regular|||on|||||&#8221; module_text_color=&#8221;#2B2B2A&#8221; module_font_size=&#8221;17px&#8221; module_letter_spacing=&#8221;0.3px&#8221; module_text_color_last_edited=&#8221;off|desktop&#8221; global_colors_info=&#8221;{}&#8221; module_text_color__hover_enabled=&#8221;off|desktop&#8221; module_text_color__hover=&#8221;#00A286&#8243; link_color__hover_enabled=&#8221;on|desktop&#8221; link_color__hover=&#8221;#00A286&#8243;][\/lwp_divi_breadcrumbs][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.24.3&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.24.3&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.24.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.24.3&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#2B2B2A&#8221; text_font_size=&#8221;17px&#8221; text_letter_spacing=&#8221;0.3px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Die 38. Baugrundtagung mit Fachausstellung Geotechnik, veranstaltet von der Deutschen Gesellschaft f\u00fcr Geotechnik e.V. (DGGT), bringt Fachleute aus der Geotechnikbranche zusammen, um neueste Erkenntnisse und Entwicklungen zu pr\u00e4sentieren und zu diskutieren. Schwerpunkte der Tagung sind unter anderem Bodenmechanik, Grundbau, Spezialtiefbau und Umweltgeotechnik.<\/p>\n<p>Unsere Teilnahme an der Baugrundtagung unterstreicht unser Engagement f\u00fcr Innovation und Qualit\u00e4t in der Geobaustoffbranche. Wir pr\u00e4sentieren unsere Produkte und L\u00f6sungen, die speziell f\u00fcr anspruchsvolle Anwendungen im Baugrund- und Umweltschutz entwickelt wurden. Im Fokus stehen hierbei unsere hochentwickelten Geokunststoffe, die h\u00f6chsten technischen und \u00f6kologischen Anforderungen gerecht werden.<\/p>\n<p>Besuchen Sie uns an unserem Stand und erfahren Sie mehr \u00fcber unsere innovativen Produkte und Dienstleistungen. Unser Expertenteam steht Ihnen f\u00fcr detaillierte Informationen und pers\u00f6nliche Gespr\u00e4che zur Verf\u00fcgung.<\/p>\n<p>Die Fachausstellung Geotechnik auf der Baugrundtagung findet in der Messe Bremen in der<span>\u00a0<\/span><strong>Findorffstr. 101, 28215 Bremen<\/strong><span>\u00a0<\/span>vom 26. &#8211; 27. September 2024 statt.<\/p>\n<p>Wir freuen uns auf die Teilnahme und darauf, unser Know-how mit Branchenkollegen und Interessierten auszutauschen.<\/p>\n<p>Weitere Informationen:<span>\u00a0<\/span><a href=\"https:\/\/www.baugrundtagung.com\/\">www.baugrundtagung.com<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Visit us at the Geotechnics exhibition at the 38th DGGT Baugrundtagung from 26 - 27 September 2024 in Bremen<\/p>","protected":false},"author":1,"featured_media":4429,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"1080","footnotes":""},"categories":[116],"tags":[],"class_list":["post-4423","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuelles"],"_links":{"self":[{"href":"https:\/\/n4zkkxq1zk.apb.spinupwp.site\/en\/wp-json\/wp\/v2\/posts\/4423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/n4zkkxq1zk.apb.spinupwp.site\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/n4zkkxq1zk.apb.spinupwp.site\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/n4zkkxq1zk.apb.spinupwp.site\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/n4zkkxq1zk.apb.spinupwp.site\/en\/wp-json\/wp\/v2\/comments?post=4423"}],"version-history":[{"count":0,"href":"https:\/\/n4zkkxq1zk.apb.spinupwp.site\/en\/wp-json\/wp\/v2\/posts\/4423\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/n4zkkxq1zk.apb.spinupwp.site\/en\/wp-json\/wp\/v2\/media\/4429"}],"wp:attachment":[{"href":"https:\/\/n4zkkxq1zk.apb.spinupwp.site\/en\/wp-json\/wp\/v2\/media?parent=4423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/n4zkkxq1zk.apb.spinupwp.site\/en\/wp-json\/wp\/v2\/categories?post=4423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/n4zkkxq1zk.apb.spinupwp.site\/en\/wp-json\/wp\/v2\/tags?post=4423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}